

{"id":15041,"date":"2020-06-09T21:07:39","date_gmt":"2020-06-10T00:07:39","guid":{"rendered":"https:\/\/avilaadvisors.com\/dev\/?p=15041"},"modified":"2021-04-14T20:34:45","modified_gmt":"2021-04-14T23:34:45","slug":"sp500-arriba-44-desde-marzo-2020-que-esperar","status":"publish","type":"post","link":"https:\/\/avilaadvisors.com\/es\/sp500-arriba-44-desde-marzo-2020-que-esperar\/","title":{"rendered":"SP500 arriba 44% desde Marzo 2020. \u00bfQu\u00e9 esperar?"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\r\n\t<div class=\"wpb_text_column wpb_content_element\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p>Inversionistas posicionados en el Largo Plazo<\/p>\n<p>\u00bfEl inicio de un nuevo mercado Alcista?<\/p>\n<p>Me permito felicitar a todos aquellos clientes que cedieron ante el temor de la correcci\u00f3n que los mercados tomaron a principios de a\u00f1o, establecieron presupuestos de gastos, entendieron la oportunidad y, con nuestra gu\u00eda, han aprovechado el sustancial desempe\u00f1o positivo de los \u00faltimos 75 d\u00edas, donde observamos un crecimiento hist\u00f3rico en los mercados financieros, ejemplo de ello, la revalorizaci\u00f3n del \u00edndice m\u00e1s seguido de la Bolsa Americana, el SP500 que se ha apreciado en un 44% desde los m\u00ednimos de marzo.<\/p>\n<p>Estas semanas han representado una oportunidad valiosa para hacer reformas en los portafolios de inversi\u00f3n, preparando estos a la nueva situaci\u00f3n de mercado y posicion\u00e1ndolos a mayores ganancias. Es de resaltar que, aquellos portafolios que se vieron afectados a principios de a\u00f1o deben haber recuperado sus valores iniciales y esperamos contin\u00faen benefici\u00e1ndose de la progresiva reapertura econ\u00f3mica, donde la espectacular y coordinada acci\u00f3n de los Bancos Centrales y Gobiernos mundiales ha sido base en la recuperaci\u00f3n de las valoraciones actuales.<\/p>\n<p>\u00bfEst\u00e1 sobredimensionado \u00e9ste crecimiento del 44%?<\/p>\n<p>Desde el inicio de esta crisis, he observado en varios medios de renombre internacional, muchas noticias alarmantes con significativas disrupciones de la realidad, en algunos casos pareciera existir una determinaci\u00f3n a psicol\u00f3gicamente crear en el lector una sensaci\u00f3n de p\u00e1nico, para generar dependencia, afianzarlo al miedo y aferrarlo a estos \u201cnoticieros\u201d. Este aspecto se resalta a\u00fan m\u00e1s con la inteligencia artificial de los buscadores, que basados en &#8220;tus intereses previos\u201d tienden a mostrarte m\u00e1s de lo que \u201cte engancha\u201d y no necesariamente lo que representa la realidad actual.<\/p>\n<p>Acad\u00e9micos mundiales aceptan que los mercados financieros tienden a ser perfectos, esto motivado a la libre participaci\u00f3n de la oferta y la demanda, que genera una formaci\u00f3n de precios basada en las expectativas de los inversionistas. Con base a este simple concepto podemos entender que las valoraciones actuales son reflejo de la visi\u00f3n futura de la reactivaci\u00f3n econ\u00f3mica y no necesariamente esta pseudo realidad que observamos a nuestro alrededor, por lo que los valores de los activos financieros representaban una oferta de remate y los inversionistas se abalanzaron a la valiosa oportunidad.<\/p>\n<p>Ante las limitadas opciones de inversi\u00f3n que se dieron a principios de marzo, motivadas por el efecto disruptivo de la pandemia mundial, que conllev\u00f3 a reducidas tasas de inter\u00e9s, da\u00f1o en el mercado laboral e inmobiliario, por s\u00f3lo mencionar algunos, establecer una estrategia basada en el largo plazo fue, sin lugar a dudas un inteligente movimiento. La expectativa de tasas de inter\u00e9s bajas en el largo plazo ha aumentado mec\u00e1nicamente el valor presente de los flujos de caja estimados futuros, haciendo que las acciones sean m\u00e1s valiosas, y relativamente m\u00e1s atractivas comparado con otros activos.<\/p>\n<p>Vemos a\u00fan interesantes oportunidades, aunque probablemente inmersas en altos niveles de volatilidad, pero mientras los Gobiernos sigan mostrando su habilidad al control de la enfermedad y de reapertura econ\u00f3mica con apoyo, los valores de los productos financieros podr\u00edan f\u00e1cilmente continuar su tendencia alcista por la simple raz\u00f3n de las limitadas opciones de inversi\u00f3n y la inyecci\u00f3n de capitales frescos por parte de los bancos centrales en un marco de bajas tasas de inter\u00e9s.<\/p>\n<p>\u00bfQu\u00e9 hacer?<\/p>\n<p>La compa\u00f1\u00eda a la cual tengo el honor de representar ha manejado Portafolios de Inversi\u00f3n durante a\u00f1os, estableciendo pol\u00edticas basadas en los perfiles de riesgo de sus clientes, ayud\u00e1ndoles en el alcance de sus metas financieras, por lo que me encuentro a tu disposici\u00f3n en apoyar y trabajar en planes personalizados basados en tus objetivos.<\/p>\n<p>En momentos de crisis, el p\u00e1nico aco<\/p>\n<p>mpa\u00f1ado con el desconocimiento de las din\u00e1micas econ\u00f3micas de los mercados, hace dif\u00edcil tomar decisiones h\u00e1biles, es all\u00ed el rol nuestro como Asesores Financieros en ayudar y superar con creces este tipo de adversidades.<\/p>\n<p>Definitivamente existen a\u00fan claras oportunidades por lo que te invito a contactarme, que con gusto puedo guiarte basado en tus necesidades personales, nuestra propuesta de trabajo est\u00e1 basada en un Ganar-Ganar.<\/p>\n<p>Muchas veces este tipo de mercado es catalogado como \u201csolo accesibles para ricos\u201d, esto no es as\u00ed, ya que contamos con productos para todos, independiente de su nacionalidad o montos de inversi\u00f3n.<\/p>\n<p>Si quieres conversar conmigo escr\u00edbeme directamente a: gustavo.patino@avilaadvisors.com o mi tel\u00e9fono +1 (305) 783-7097.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Me permito felicitar a todos aquellos clientes que cedieron ante el temor de la correcci\u00f3n que los mercados&#8230;<\/p>","protected":false},"author":1,"featured_media":15174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/avilaadvisors.com\/es\/wp-json\/wp\/v2\/posts\/15041"}],"collection":[{"href":"https:\/\/avilaadvisors.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avilaadvisors.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avilaadvisors.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/avilaadvisors.com\/es\/wp-json\/wp\/v2\/comments?post=15041"}],"version-history":[{"count":2,"href":"https:\/\/avilaadvisors.com\/es\/wp-json\/wp\/v2\/posts\/15041\/revisions"}],"predecessor-version":[{"id":15065,"href":"https:\/\/avilaadvisors.com\/es\/wp-json\/wp\/v2\/posts\/15041\/revisions\/15065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avilaadvisors.com\/es\/wp-json\/wp\/v2\/media\/15174"}],"wp:attachment":[{"href":"https:\/\/avilaadvisors.com\/es\/wp-json\/wp\/v2\/media?parent=15041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avilaadvisors.com\/es\/wp-json\/wp\/v2\/categories?post=15041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avilaadvisors.com\/es\/wp-json\/wp\/v2\/tags?post=15041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}